{"id":240450,"date":"2024-02-06T20:46:58","date_gmt":"2024-02-06T19:46:58","guid":{"rendered":"https:\/\/luxecarexport.fr\/?page_id=240450"},"modified":"2026-03-23T14:24:10","modified_gmt":"2026-03-23T13:24:10","slug":"tarifs-exportation-vehicules-de-dubai","status":"publish","type":"page","link":"https:\/\/luxecarexport.fr\/es\/tarifs-exportation-vehicules-de-dubai\/","title":{"rendered":"Tarifs exportation de v\u00e9hicules de Dubai"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbrgba(0,0,0,0.3)\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/luxecarexport.fr\/wp-content\/uploads\/2026\/03\/Frais-pour-exporter-son-vehicule-depuis-Dubai-vers-la-France-ou-le-monde-entier-scaled.jpg\u00a0\u00bb background_blend=\u00a0\u00bboverlay\u00a0\u00bb height=\u00a0\u00bb100vh\u00a0\u00bb background_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb background_image_phone=\u00a0\u00bbhttps:\/\/luxecarexport.fr\/wp-content\/uploads\/2026\/03\/Frais-pour-exporter-son-vehicule-depuis-Dubai-vers-la-France-ou-le-monde-entier-2-scaled.jpg\u00a0\u00bb background_enable_image_phone=\u00a0\u00bbon\u00a0\u00bb border_radii=\u00a0\u00bboff|||40px|40px\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width_tablet=\u00a0\u00bb70%\u00a0\u00bb max_width_phone=\u00a0\u00bb100%\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb250px||||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb170px||||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb150px||||false|false\u00a0\u00bb animation_style=\u00a0\u00bbfade\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb header_text_align=\u00a0\u00bbleft\u00a0\u00bb header_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_font_size=\u00a0\u00bb50px\u00a0\u00bb header_line_height=\u00a0\u00bb1.1em\u00a0\u00bb header_2_font=\u00a0\u00bbSackersGothicStd-Med||||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb50px\u00a0\u00bb header_3_font_size=\u00a0\u00bb50px\u00a0\u00bb header_4_font_size=\u00a0\u00bb50px\u00a0\u00bb header_5_font_size=\u00a0\u00bb50px\u00a0\u00bb header_6_font_size=\u00a0\u00bb50px\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_font_size_phone=\u00a0\u00bb40px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb40px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_4_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_4_font_size_phone=\u00a0\u00bb40px\u00a0\u00bb header_4_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_5_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_5_font_size_phone=\u00a0\u00bb40px\u00a0\u00bb header_5_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_6_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_6_font_size_phone=\u00a0\u00bb40px\u00a0\u00bb header_6_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1 style=\"text-align: center;\">Los gastos con el fin de exportar el veh\u00edculo de Dubai a Francia, o en otro lugar<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_font_size=\u00a0\u00bb40px\u00a0\u00bb header_2_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#000000&Prime; header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>2500\u20ac*<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_font_size=\u00a0\u00bb25px\u00a0\u00bb header_2_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#000000&Prime; header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>lugar en el contenedor<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbFactor A Regular||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#000000&Prime; header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>La tasa de exportaci\u00f3n de contenedores de Dubai <strong>actuellement en 2026 au prix d&rsquo;environ 2500\u20ac.<\/strong> Usted puede pagar en el lugar de su ubicaci\u00f3n en el contenedor.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_font_size=\u00a0\u00bb40px\u00a0\u00bb header_2_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#000000&Prime; header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>500\u20ac<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_font_size=\u00a0\u00bb25px\u00a0\u00bb header_2_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#000000&Prime; header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>certificado de exportaci\u00f3n<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbFactor A Regular||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb link_font=\u00a0\u00bb||||on||||\u00a0\u00bb link_text_color=\u00a0\u00bb#000000&Prime; header_2_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#000000&Prime; header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Exportar simplemente y legalmente en su veh\u00edculo gracias a el documento oficial de la <a href=\"https:\/\/luxecarexport.fr\/es\/foire-aux-questions\/\" title=\"RTA Dubai\">RTA<\/a>. Usted puede viajar a Dubai durante su estancia, si usted decide venir en el sitio.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_font_size=\u00a0\u00bb40px\u00a0\u00bb header_2_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#000000&Prime; header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>1390\u20ac<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_font_size=\u00a0\u00bb25px\u00a0\u00bb header_2_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#000000&Prime; header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>nuestros gastos de gesti\u00f3n<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbFactor A Regular||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb header_2_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#000000&Prime; header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>El precio de costo de la log\u00edstica en el sitio, que puede agregar cargos adicionales para viajar relacionadas con la compra de repuestos o mantenimiento.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_slider _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb height=\u00a0\u00bb70vh\u00a0\u00bb height_tablet=\u00a0\u00bb70vh\u00a0\u00bb height_phone=\u00a0\u00bb50vh\u00a0\u00bb height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb border_radii=\u00a0\u00bbon|40px|40px|40px|40px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_slide _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/luxecarexport.fr\/wp-content\/uploads\/2026\/02\/Luxe-Car-Export-tarifs-exportation-depuis-Dubai-scaled.jpg\u00a0\u00bb background_enable_image=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_transition=\u00a0\u00bbon\u00a0\u00bb][\/et_pb_slide][\/et_pb_slider][et_pb_button button_url=\u00a0\u00bbhttps:\/\/luxecarexport.fr\/simulation-exportation-vehicule-dubai\/\u00a0\u00bb button_text=\u00a0\u00bbSimulation importation v\u00e9hicule Dubai\u00a0\u00bb button_alignment=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_tablet=\u00a0\u00bbleft\u00a0\u00bb button_alignment_phone=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bboff|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb20px\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bb#000000&Prime; button_border_color=\u00a0\u00bb#000000&Prime; button_border_radius=\u00a0\u00bb20px\u00a0\u00bb button_font=\u00a0\u00bbFactor A Light||||||||\u00a0\u00bb button_use_icon=\u00a0\u00bboff\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb35px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#000000&Prime; header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\">Grille tarifaire selon le pays d&rsquo;exp\u00e9dition<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_code _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<style><!-- [et_pb_line_break_holder] -->  .ship-outer {<!-- [et_pb_line_break_holder] -->    font-family: 'Factor A', sans-serif;<!-- [et_pb_line_break_holder] -->    background: var(--color-background-secondary, #F4F6FA);<!-- [et_pb_line_break_holder] -->    border-radius: 16px;<!-- [et_pb_line_break_holder] -->    padding: 32px 28px;<!-- [et_pb_line_break_holder] -->    max-width: 100%;<!-- [et_pb_line_break_holder] -->    box-sizing: border-box;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  .ship-header {<!-- [et_pb_line_break_holder] -->    margin: 0 0 24px;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  .ship-title {<!-- [et_pb_line_break_holder] -->    font-family: 'Factor A Bold', sans-serif;<!-- [et_pb_line_break_holder] -->    font-size: 16px;<!-- [et_pb_line_break_holder] -->    font-weight: 700;<!-- [et_pb_line_break_holder] -->    color: var(--color-text-primary, #1A1F2E);<!-- [et_pb_line_break_holder] -->    margin: 0 0 6px;<!-- [et_pb_line_break_holder] -->    display: flex;<!-- [et_pb_line_break_holder] -->    align-items: center;<!-- [et_pb_line_break_holder] -->    gap: 8px;<!-- [et_pb_line_break_holder] -->    flex-wrap: wrap;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  .ship-badge {<!-- [et_pb_line_break_holder] -->    font-family: 'Factor A Regular', sans-serif;<!-- [et_pb_line_break_holder] -->    font-size: 11px;<!-- [et_pb_line_break_holder] -->    font-weight: 600;<!-- [et_pb_line_break_holder] -->    background: var(--color-text-primary, #1A1F2E);<!-- [et_pb_line_break_holder] -->    color: var(--color-background-primary, #ffffff);<!-- [et_pb_line_break_holder] -->    padding: 3px 9px;<!-- [et_pb_line_break_holder] -->    border-radius: 20px;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  .ship-subtitle {<!-- [et_pb_line_break_holder] -->    font-family: 'Factor A Regular', sans-serif;<!-- [et_pb_line_break_holder] -->    font-size: 13px;<!-- [et_pb_line_break_holder] -->    font-style: italic;<!-- [et_pb_line_break_holder] -->    color: var(--color-text-secondary, #8A94A6);<!-- [et_pb_line_break_holder] -->    margin: 0;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  .ship-table {<!-- [et_pb_line_break_holder] -->    width: 100%;<!-- [et_pb_line_break_holder] -->    border-collapse: collapse;<!-- [et_pb_line_break_holder] -->    table-layout: fixed;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  .ship-table colgroup col:nth-child(1) { width: 70%; }<!-- [et_pb_line_break_holder] -->  .ship-table colgroup col:nth-child(2) { width: 30%; }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  .ship-table thead tr {<!-- [et_pb_line_break_holder] -->    border-bottom: 1.5px solid var(--color-border-secondary, #E2E8F4);<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  .ship-table thead th {<!-- [et_pb_line_break_holder] -->    font-family: 'Factor A Bold', sans-serif;<!-- [et_pb_line_break_holder] -->    font-size: 11px;<!-- [et_pb_line_break_holder] -->    font-weight: 700;<!-- [et_pb_line_break_holder] -->    letter-spacing: 0.08em;<!-- [et_pb_line_break_holder] -->    text-transform: uppercase;<!-- [et_pb_line_break_holder] -->    color: var(--color-text-secondary, #8A94A6);<!-- [et_pb_line_break_holder] -->    padding: 0 0 12px;<!-- [et_pb_line_break_holder] -->    text-align: left;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  .ship-table thead th:last-child {<!-- [et_pb_line_break_holder] -->    text-align: right;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  .ship-table tbody tr {<!-- [et_pb_line_break_holder] -->    border-bottom: 1px solid var(--color-border-tertiary, #EEF0F5);<!-- [et_pb_line_break_holder] -->    transition: background 0.15s ease;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  .ship-table tbody tr:last-child {<!-- [et_pb_line_break_holder] -->    border-bottom: none;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  .ship-table tbody tr:hover {<!-- [et_pb_line_break_holder] -->    background: var(--color-background-primary, #ffffff);<!-- [et_pb_line_break_holder] -->    border-radius: 8px;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  .ship-table tbody td {<!-- [et_pb_line_break_holder] -->    font-family: 'Factor A Regular', sans-serif;<!-- [et_pb_line_break_holder] -->    font-size: 14px;<!-- [et_pb_line_break_holder] -->    color: var(--color-text-secondary, #4A5568);<!-- [et_pb_line_break_holder] -->    padding: 14px 0;<!-- [et_pb_line_break_holder] -->    vertical-align: top;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  .ship-table tbody td.td-price {<!-- [et_pb_line_break_holder] -->    font-family: 'Factor A Bold', sans-serif;<!-- [et_pb_line_break_holder] -->    font-size: 15px;<!-- [et_pb_line_break_holder] -->    font-weight: 700;<!-- [et_pb_line_break_holder] -->    color: var(--color-text-primary, #1A1F2E);<!-- [et_pb_line_break_holder] -->    text-align: right;<!-- [et_pb_line_break_holder] -->    white-space: nowrap;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  .td-countries {<!-- [et_pb_line_break_holder] -->    display: flex;<!-- [et_pb_line_break_holder] -->    flex-direction: column;<!-- [et_pb_line_break_holder] -->    gap: 4px;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  .td-countries span {<!-- [et_pb_line_break_holder] -->    font-size: 13px;<!-- [et_pb_line_break_holder] -->    line-height: 1.5;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  .td-note {<!-- [et_pb_line_break_holder] -->    font-size: 11px;<!-- [et_pb_line_break_holder] -->    color: var(--color-text-secondary, #8A94A6);<!-- [et_pb_line_break_holder] -->    font-style: italic;<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  @media (max-width: 500px) {<!-- [et_pb_line_break_holder] -->    .ship-outer {<!-- [et_pb_line_break_holder] -->      padding: 24px 16px;<!-- [et_pb_line_break_holder] -->    }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->    .ship-table,<!-- [et_pb_line_break_holder] -->    .ship-table thead,<!-- [et_pb_line_break_holder] -->    .ship-table tbody,<!-- [et_pb_line_break_holder] -->    .ship-table th,<!-- [et_pb_line_break_holder] -->    .ship-table td,<!-- [et_pb_line_break_holder] -->    .ship-table tr {<!-- [et_pb_line_break_holder] -->      display: block;<!-- [et_pb_line_break_holder] -->      width: 100%;<!-- [et_pb_line_break_holder] -->    }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->    .ship-table thead {<!-- [et_pb_line_break_holder] -->      display: none;<!-- [et_pb_line_break_holder] -->    }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->    .ship-table tbody tr {<!-- [et_pb_line_break_holder] -->      border: 1px solid var(--color-border-tertiary, #EEF0F5);<!-- [et_pb_line_break_holder] -->      border-radius: 10px;<!-- [et_pb_line_break_holder] -->      margin-bottom: 10px;<!-- [et_pb_line_break_holder] -->      padding: 12px 14px;<!-- [et_pb_line_break_holder] -->      background: var(--color-background-primary, #ffffff);<!-- [et_pb_line_break_holder] -->    }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->    .ship-table tbody td {<!-- [et_pb_line_break_holder] -->      padding: 4px 0;<!-- [et_pb_line_break_holder] -->      border: none;<!-- [et_pb_line_break_holder] -->    }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->    .ship-table tbody td::before {<!-- [et_pb_line_break_holder] -->      content: attr(data-label);<!-- [et_pb_line_break_holder] -->      display: block;<!-- [et_pb_line_break_holder] -->      font-size: 10px;<!-- [et_pb_line_break_holder] -->      font-weight: 700;<!-- [et_pb_line_break_holder] -->      letter-spacing: 0.08em;<!-- [et_pb_line_break_holder] -->      text-transform: uppercase;<!-- [et_pb_line_break_holder] -->      color: var(--color-text-secondary, #8A94A6);<!-- [et_pb_line_break_holder] -->      margin-bottom: 2px;<!-- [et_pb_line_break_holder] -->    }<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->    .ship-table tbody td.td-price {<!-- [et_pb_line_break_holder] -->      text-align: left;<!-- [et_pb_line_break_holder] -->      font-size: 18px;<!-- [et_pb_line_break_holder] -->      padding-top: 8px;<!-- [et_pb_line_break_holder] -->    }<!-- [et_pb_line_break_holder] -->  }<!-- [et_pb_line_break_holder] --><\/style>\n<p><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><\/p>\n<div class=\"ship-outer\"><!-- [et_pb_line_break_holder] -->  <\/p>\n<div class=\"ship-header\"><!-- [et_pb_line_break_holder] -->    <pee class=\"ship-title\"><!-- [et_pb_line_break_holder] -->      Tarifs groupage<!-- [et_pb_line_break_holder] -->      <span class=\"ship-badge\">1 v\u00e9hicule<\/span><!-- [et_pb_line_break_holder] -->    <\/pee><!-- [et_pb_line_break_holder] -->    <pee class=\"ship-subtitle\"><!-- [et_pb_line_break_holder] -->      Les tarifs ci-dessous sont en groupage, et peuvent varier selon le mois d&rsquo;envoi.<!-- [et_pb_line_break_holder] -->    <\/pee><!-- [et_pb_line_break_holder] -->  <\/div>\n<p><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->  <\/p>\n<table class=\"ship-table\"><!-- [et_pb_line_break_holder] -->    <\/p>\n<colgroup><!-- [et_pb_line_break_holder] -->      <\/p>\n<col \/>\n<col \/><!-- [et_pb_line_break_holder] -->    <\/colgroup>\n<p><!-- [et_pb_line_break_holder] -->    <\/p>\n<thead><!-- [et_pb_line_break_holder] -->      <\/p>\n<tr><!-- [et_pb_line_break_holder] -->        <\/p>\n<th>Pays<\/th>\n<p><!-- [et_pb_line_break_holder] -->        <\/p>\n<th>Tarif<\/th>\n<p><!-- [et_pb_line_break_holder] -->      <\/tr>\n<p><!-- [et_pb_line_break_holder] -->    <\/thead>\n<p><!-- [et_pb_line_break_holder] -->    <\/p>\n<tbody><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->      <\/p>\n<tr><!-- [et_pb_line_break_holder] -->        <\/p>\n<td data-label=\"Pays\"><!-- [et_pb_line_break_holder] -->          <\/p>\n<div class=\"td-countries\"><!-- [et_pb_line_break_holder] -->            <span>\ud83c\uddeb\ud83c\uddf7 France<\/span><!-- [et_pb_line_break_holder] -->            <span>\ud83c\uddea\ud83c\uddf8 Espagne<\/span><!-- [et_pb_line_break_holder] -->            <span>\ud83c\uddee\ud83c\uddf9 Italie<\/span><!-- [et_pb_line_break_holder] -->            <span>\ud83c\uddf9\ud83c\uddf3 Tunisie<\/span><!-- [et_pb_line_break_holder] -->            <span>\ud83c\udde8\ud83c\uddee C\u00f4te d&rsquo;Ivoire<\/span><!-- [et_pb_line_break_holder] -->            <span>\ud83c\udde7\ud83c\uddef B\u00e9nin<\/span><!-- [et_pb_line_break_holder] -->            <span>\ud83c\udde8\ud83c\uddf2 Cameroun<\/span><!-- [et_pb_line_break_holder] -->            <span>\ud83c\udde9\ud83c\uddff Alg\u00e9rie<\/span><!-- [et_pb_line_break_holder] -->          <\/div>\n<p><!-- [et_pb_line_break_holder] -->        <\/td>\n<p><!-- [et_pb_line_break_holder] -->        <\/p>\n<td class=\"td-price\" data-label=\"Tarif\">2 500 \u20ac<\/td>\n<p><!-- [et_pb_line_break_holder] -->      <\/tr>\n<p><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->      <\/p>\n<tr><!-- [et_pb_line_break_holder] -->        <\/p>\n<td data-label=\"Pays\"><!-- [et_pb_line_break_holder] -->          <\/p>\n<div class=\"td-countries\"><!-- [et_pb_line_break_holder] -->            <span>\ud83c\udde7\ud83c\uddea Belgique<\/span><!-- [et_pb_line_break_holder] -->          <\/div>\n<p><!-- [et_pb_line_break_holder] -->        <\/td>\n<p><!-- [et_pb_line_break_holder] -->        <\/p>\n<td class=\"td-price\" data-label=\"Tarif\">2 900 \u20ac<\/td>\n<p><!-- [et_pb_line_break_holder] -->      <\/tr>\n<p><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->      <\/p>\n<tr><!-- [et_pb_line_break_holder] -->        <\/p>\n<td data-label=\"Pays\"><!-- [et_pb_line_break_holder] -->          <\/p>\n<div class=\"td-countries\"><!-- [et_pb_line_break_holder] -->            <span>\ud83c\uddfa\ud83c\uddf8 \u00c9tats-Unis<\/span><!-- [et_pb_line_break_holder] -->            <span class=\"td-note\">(New Jersey)<\/span><!-- [et_pb_line_break_holder] -->          <\/div>\n<p><!-- [et_pb_line_break_holder] -->        <\/td>\n<p><!-- [et_pb_line_break_holder] -->        <\/p>\n<td class=\"td-price\" data-label=\"Tarif\">3 000 \u20ac<\/td>\n<p><!-- [et_pb_line_break_holder] -->      <\/tr>\n<p><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->      <\/p>\n<tr><!-- [et_pb_line_break_holder] -->        <\/p>\n<td data-label=\"Pays\"><!-- [et_pb_line_break_holder] -->          <\/p>\n<div class=\"td-countries\"><!-- [et_pb_line_break_holder] -->            <span>\ud83c\uddf2\ud83c\udde6 Maroc<\/span><!-- [et_pb_line_break_holder] -->          <\/div>\n<p><!-- [et_pb_line_break_holder] -->        <\/td>\n<p><!-- [et_pb_line_break_holder] -->        <\/p>\n<td class=\"td-price\" data-label=\"Tarif\">3 300 \u20ac<\/td>\n<p><!-- [et_pb_line_break_holder] -->      <\/tr>\n<p><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->      <\/p>\n<tr><!-- [et_pb_line_break_holder] -->        <\/p>\n<td data-label=\"Pays\"><!-- [et_pb_line_break_holder] -->          <\/p>\n<div class=\"td-countries\"><!-- [et_pb_line_break_holder] -->            <span>\ud83c\uddec\ud83c\uddf3 Guin\u00e9e<\/span><!-- [et_pb_line_break_holder] -->          <\/div>\n<p><!-- [et_pb_line_break_holder] -->        <\/td>\n<p><!-- [et_pb_line_break_holder] -->        <\/p>\n<td class=\"td-price\" data-label=\"Tarif\">3 900 \u20ac<\/td>\n<p><!-- [et_pb_line_break_holder] -->      <\/tr>\n<p><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->      <\/p>\n<tr><!-- [et_pb_line_break_holder] -->        <\/p>\n<td data-label=\"Pays\"><!-- [et_pb_line_break_holder] -->          <\/p>\n<div class=\"td-countries\"><!-- [et_pb_line_break_holder] -->            <span>\ud83c\uddf5\ud83c\uddeb Polyn\u00e9sie fran\u00e7aise<\/span><!-- [et_pb_line_break_holder] -->            <span class=\"td-note\">(Papeete)<\/span><!-- [et_pb_line_break_holder] -->          <\/div>\n<p><!-- [et_pb_line_break_holder] -->        <\/td>\n<p><!-- [et_pb_line_break_holder] -->        <\/p>\n<td class=\"td-price\" data-label=\"Tarif\">4 300 \u20ac<\/td>\n<p><!-- [et_pb_line_break_holder] -->      <\/tr>\n<p><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->      <\/p>\n<tr><!-- [et_pb_line_break_holder] -->        <\/p>\n<td data-label=\"Pays\"><!-- [et_pb_line_break_holder] -->          <\/p>\n<div class=\"td-countries\"><!-- [et_pb_line_break_holder] -->            <span>\ud83c\udded\ud83c\uddf9 Ha\u00efti<\/span><!-- [et_pb_line_break_holder] -->          <\/div>\n<p><!-- [et_pb_line_break_holder] -->        <\/td>\n<p><!-- [et_pb_line_break_holder] -->        <\/p>\n<td class=\"td-price\" data-label=\"Tarif\">4 600 \u20ac<\/td>\n<p><!-- [et_pb_line_break_holder] -->      <\/tr>\n<p><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->    <\/tbody>\n<p><!-- [et_pb_line_break_holder] -->  <\/table>\n<p><!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbFactor A Regular||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb link_font=\u00a0\u00bb||||on||||\u00a0\u00bb link_text_color=\u00a0\u00bb#000000&Prime; header_2_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#000000&Prime; header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: left;\">\u2022 Tarifs groupage variables selon la p\u00e9riode d\u2019exp\u00e9dition et la disponibilit\u00e9.<br \/>\u2022 Assurance maritime en option, en suppl\u00e9ment si demand\u00e9e.<br \/>\u2022 Frais d\u2019annulation : 300 USD par conteneur si annulation apr\u00e8s confirmation.<br \/>\u2022 Sous r\u00e9serve de disponibilit\u00e9 d\u2019espace et d\u2019\u00e9quipement au moment de la r\u00e9servation.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb35px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#000000&Prime; header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\">Le service d&rsquo;importation de v\u00e9hicule\u00a0 inclus :<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_5,1_5,1_5,1_5,1_5&Prime; _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; custom_padding=\u00a0\u00bb40px|20px|40px|20px|true|true\u00a0\u00bb border_radii=\u00a0\u00bbon|40px|40px|40px|40px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_icon font_icon=\u00a0\u00bb&#xe037;||divi||400&Prime; icon_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb icon_width=\u00a0\u00bb50px\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_icon][et_pb_text _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb link_text_color=\u00a0\u00bb#000000&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\">Gesti\u00f3n capaz de importar<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_icon font_icon=\u00a0\u00bb&#xf87c;||fa||900&Prime; icon_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb icon_width=\u00a0\u00bb50px\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_icon][et_pb_text _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb link_text_color=\u00a0\u00bb#000000&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\">Enviar fotos y video del veh\u00edculo<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_icon font_icon=\u00a0\u00bb&#xe0d9;||divi||400&Prime; icon_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb icon_width=\u00a0\u00bb50px\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_icon][et_pb_text _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb link_text_color=\u00a0\u00bb#000000&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\">La facilidad y seguridad para su proyecto<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_icon font_icon=\u00a0\u00bb&#xf0c5;||fa||900&Prime; icon_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb icon_width=\u00a0\u00bb50px\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_icon][et_pb_text _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb link_text_color=\u00a0\u00bb#000000&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\">Los procedimientos administrativos<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_icon font_icon=\u00a0\u00bb&#xf124;||fa||900&Prime; icon_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb icon_width=\u00a0\u00bb50px\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_icon][et_pb_text _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb link_text_color=\u00a0\u00bb#000000&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\">De viaje incluido<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb35px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#000000&Prime; header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\">Listas para su nuevo veh\u00edculo ?<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/luxecarexport.fr\/wp-content\/uploads\/2024\/03\/importer-votre-vehicule-facilement-depuis-dubai-luxe-car-export.jpeg\u00a0\u00bb alt=\u00a0\u00bbimporter-votre-ve\u0301hicule-facilement-depuis-dubai-luxe-car-export\u00a0\u00bb title_text=\u00a0\u00bbimporter-votre-ve\u0301hicule-facilement-depuis-dubai-luxe-car-export\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb border_radii=\u00a0\u00bbon|40px|40px|40px|40px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.24.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbFactor A Regular||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb link_font=\u00a0\u00bb||||on||||\u00a0\u00bb link_text_color=\u00a0\u00bb#000000&Prime; header_2_font=\u00a0\u00bbFactor A Bold||||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#000000&Prime; header_2_font_size=\u00a0\u00bb30px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><strong>Listos para comprometerse a la compra del veh\u00edculo de sus sue\u00f1os directamente desde Dubai?<\/strong><\/p>\n<p>\u29bf Descargar la aplicaci\u00f3n <a href=\"https:\/\/apps.apple.com\/ae\/app\/dubizzle\/id892172848\" title=\"Dubizzle\">Dubizzle<\/a> o ir en el <a href=\"https:\/\/dubai.dubizzle.com\/\" title=\"sitio web\">sitio web<\/a><\/p>\n<p>\u29bf Seleccione su veh\u00edculo listado<\/p>\n<p>\u29bf Le proporcionaremos con un presupuesto para la ayuda de la convocatoria<\/p>\n<p>\u29bf El veh\u00edculo es inspeccionado en el sitio<\/p>\n<p>\u29bf De comprar el veh\u00edculo est\u00e1 asegurado con el pago de forma remota o en sitio<\/p>\n<p>\u29bf Tr\u00e1mites de exportaci\u00f3n y ponga en un recipiente con el destino de su elecci\u00f3n.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/luxecarexport.fr\/contact\/\u00a0\u00bb button_text=\u00a0\u00bbJ&rsquo;importe mon v\u00e9hicule maintenant\u00a0\u00bb button_alignment=\u00a0\u00bbleft\u00a0\u00bb button_alignment_tablet=\u00a0\u00bbleft\u00a0\u00bb button_alignment_phone=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb20px\u00a0\u00bb button_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_bg_color=\u00a0\u00bb#000000&Prime; button_border_color=\u00a0\u00bb#000000&Prime; button_border_radius=\u00a0\u00bb20px\u00a0\u00bb button_font=\u00a0\u00bbFactor A Light||||||||\u00a0\u00bb button_use_icon=\u00a0\u00bboff\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>","protected":false},"excerpt":{"rendered":"<p>Les frais pour exporter son v\u00e9hicule\u00a0 depuis Dubai vers la\u00a0France ou ailleurs2500\u20ac*place dans le conteneurLe tarif d&rsquo;exportation en conteneur depuis Dubai est actuellement en 2026 au prix d&rsquo;environ 2500\u20ac. Vous pouvez payer sur place votre emplacement dans le conteneur.500\u20accertificat d&rsquo;exportExporter simplement et l\u00e9galement votre v\u00e9hicule gr\u00e2ce au document officiel de la RTA. Vous pouvez circuler [&hellip;]<\/p>","protected":false},"author":1,"featured_media":241200,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"class_list":["post-240450","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quel est le tarif pour exporter un v\u00e9hicule de Dubai ?<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez toutes les informations sur le co\u00fbt d&#039;une exportation de v\u00e9hicule situ\u00e9 \u00e0 Dubai, aux Emirats vers l&#039;\u00e9tranger.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/luxecarexport.fr\/es\/tarifs-exportation-vehicules-de-dubai\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quel est le tarif pour exporter un v\u00e9hicule de Dubai ?\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez toutes les informations sur le co\u00fbt d&#039;une exportation de v\u00e9hicule situ\u00e9 \u00e0 Dubai, aux Emirats vers l&#039;\u00e9tranger.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/luxecarexport.fr\/es\/tarifs-exportation-vehicules-de-dubai\/\" \/>\n<meta property=\"og:site_name\" content=\"Luxe Car Export - Importer un v\u00e9hicule de Dubai\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T13:24:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/luxecarexport.fr\/wp-content\/uploads\/2026\/03\/Frais-pour-exporter-son-vehicule-depuis-Dubai-vers-la-France-ou-le-monde-entier-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1999\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/luxecarexport.fr\\\/tarifs-exportation-vehicules-de-dubai\\\/\",\"url\":\"https:\\\/\\\/luxecarexport.fr\\\/tarifs-exportation-vehicules-de-dubai\\\/\",\"name\":\"Quel est le tarif pour exporter un v\u00e9hicule de Dubai ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/luxecarexport.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/luxecarexport.fr\\\/tarifs-exportation-vehicules-de-dubai\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/luxecarexport.fr\\\/tarifs-exportation-vehicules-de-dubai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/luxecarexport.fr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Frais-pour-exporter-son-vehicule-depuis-Dubai-vers-la-France-ou-le-monde-entier-scaled.jpg\",\"datePublished\":\"2024-02-06T19:46:58+00:00\",\"dateModified\":\"2026-03-23T13:24:10+00:00\",\"description\":\"D\u00e9couvrez toutes les informations sur le co\u00fbt d'une exportation de v\u00e9hicule situ\u00e9 \u00e0 Dubai, aux Emirats vers l'\u00e9tranger.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/luxecarexport.fr\\\/tarifs-exportation-vehicules-de-dubai\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/luxecarexport.fr\\\/tarifs-exportation-vehicules-de-dubai\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/luxecarexport.fr\\\/tarifs-exportation-vehicules-de-dubai\\\/#primaryimage\",\"url\":\"https:\\\/\\\/luxecarexport.fr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Frais-pour-exporter-son-vehicule-depuis-Dubai-vers-la-France-ou-le-monde-entier-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/luxecarexport.fr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Frais-pour-exporter-son-vehicule-depuis-Dubai-vers-la-France-ou-le-monde-entier-scaled.jpg\",\"width\":2560,\"height\":1999,\"caption\":\"Frais pour exporter son ve\u0301hicule\u00a0depuis Dubai vers la\u00a0France ou le monde entier\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/luxecarexport.fr\\\/tarifs-exportation-vehicules-de-dubai\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/luxecarexport.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tarifs exportation de v\u00e9hicules de Dubai\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/luxecarexport.fr\\\/#website\",\"url\":\"https:\\\/\\\/luxecarexport.fr\\\/\",\"name\":\"Luxe Car Export - Importer votre v\u00e9hicule de Dubai\",\"description\":\"Site internet de la soci\u00e9t\u00e9 Luxe Car Export - sp\u00e9cialiste de l&#039;importation de v\u00e9hicules en provenance du Dubai, des Emirats.\",\"publisher\":{\"@id\":\"https:\\\/\\\/luxecarexport.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/luxecarexport.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/luxecarexport.fr\\\/#organization\",\"name\":\"Luxe Car Export - Importer votre v\u00e9hicule de Dubai\",\"url\":\"https:\\\/\\\/luxecarexport.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/luxecarexport.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/luxecarexport.fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/favicon-luxe-car-export.png\",\"contentUrl\":\"https:\\\/\\\/luxecarexport.fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/favicon-luxe-car-export.png\",\"width\":512,\"height\":512,\"caption\":\"Luxe Car Export - Importer votre v\u00e9hicule de Dubai\"},\"image\":{\"@id\":\"https:\\\/\\\/luxecarexport.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/wa.me\\\/c\\\/971504542788\",\"https:\\\/\\\/www.instagram.com\\\/luxecarexport\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@luxecarexport\",\"https:\\\/\\\/www.snapchat.com\\\/add\\\/luxecarexport23\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quel est le tarif pour exporter un v\u00e9hicule de Dubai ?","description":"D\u00e9couvrez toutes les informations sur le co\u00fbt d'une exportation de v\u00e9hicule situ\u00e9 \u00e0 Dubai, aux Emirats vers l'\u00e9tranger.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/luxecarexport.fr\/es\/tarifs-exportation-vehicules-de-dubai\/","og_locale":"es_ES","og_type":"article","og_title":"Quel est le tarif pour exporter un v\u00e9hicule de Dubai ?","og_description":"D\u00e9couvrez toutes les informations sur le co\u00fbt d'une exportation de v\u00e9hicule situ\u00e9 \u00e0 Dubai, aux Emirats vers l'\u00e9tranger.","og_url":"https:\/\/luxecarexport.fr\/es\/tarifs-exportation-vehicules-de-dubai\/","og_site_name":"Luxe Car Export - Importer un v\u00e9hicule de Dubai","article_modified_time":"2026-03-23T13:24:10+00:00","og_image":[{"width":2560,"height":1999,"url":"https:\/\/luxecarexport.fr\/wp-content\/uploads\/2026\/03\/Frais-pour-exporter-son-vehicule-depuis-Dubai-vers-la-France-ou-le-monde-entier-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/luxecarexport.fr\/tarifs-exportation-vehicules-de-dubai\/","url":"https:\/\/luxecarexport.fr\/tarifs-exportation-vehicules-de-dubai\/","name":"Quel est le tarif pour exporter un v\u00e9hicule de Dubai ?","isPartOf":{"@id":"https:\/\/luxecarexport.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/luxecarexport.fr\/tarifs-exportation-vehicules-de-dubai\/#primaryimage"},"image":{"@id":"https:\/\/luxecarexport.fr\/tarifs-exportation-vehicules-de-dubai\/#primaryimage"},"thumbnailUrl":"https:\/\/luxecarexport.fr\/wp-content\/uploads\/2026\/03\/Frais-pour-exporter-son-vehicule-depuis-Dubai-vers-la-France-ou-le-monde-entier-scaled.jpg","datePublished":"2024-02-06T19:46:58+00:00","dateModified":"2026-03-23T13:24:10+00:00","description":"D\u00e9couvrez toutes les informations sur le co\u00fbt d'une exportation de v\u00e9hicule situ\u00e9 \u00e0 Dubai, aux Emirats vers l'\u00e9tranger.","breadcrumb":{"@id":"https:\/\/luxecarexport.fr\/tarifs-exportation-vehicules-de-dubai\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/luxecarexport.fr\/tarifs-exportation-vehicules-de-dubai\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/luxecarexport.fr\/tarifs-exportation-vehicules-de-dubai\/#primaryimage","url":"https:\/\/luxecarexport.fr\/wp-content\/uploads\/2026\/03\/Frais-pour-exporter-son-vehicule-depuis-Dubai-vers-la-France-ou-le-monde-entier-scaled.jpg","contentUrl":"https:\/\/luxecarexport.fr\/wp-content\/uploads\/2026\/03\/Frais-pour-exporter-son-vehicule-depuis-Dubai-vers-la-France-ou-le-monde-entier-scaled.jpg","width":2560,"height":1999,"caption":"Frais pour exporter son ve\u0301hicule\u00a0depuis Dubai vers la\u00a0France ou le monde entier"},{"@type":"BreadcrumbList","@id":"https:\/\/luxecarexport.fr\/tarifs-exportation-vehicules-de-dubai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/luxecarexport.fr\/"},{"@type":"ListItem","position":2,"name":"Tarifs exportation de v\u00e9hicules de Dubai"}]},{"@type":"WebSite","@id":"https:\/\/luxecarexport.fr\/#website","url":"https:\/\/luxecarexport.fr\/","name":"Luxe Car Export - Importer votre v\u00e9hicule de Dubai","description":"Site internet de la soci\u00e9t\u00e9 Luxe Car Export - sp\u00e9cialiste de l&#039;importation de v\u00e9hicules en provenance du Dubai, des Emirats.","publisher":{"@id":"https:\/\/luxecarexport.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/luxecarexport.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/luxecarexport.fr\/#organization","name":"Luxe Car Export - Importer votre v\u00e9hicule de Dubai","url":"https:\/\/luxecarexport.fr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/luxecarexport.fr\/#\/schema\/logo\/image\/","url":"https:\/\/luxecarexport.fr\/wp-content\/uploads\/2024\/02\/favicon-luxe-car-export.png","contentUrl":"https:\/\/luxecarexport.fr\/wp-content\/uploads\/2024\/02\/favicon-luxe-car-export.png","width":512,"height":512,"caption":"Luxe Car Export - Importer votre v\u00e9hicule de Dubai"},"image":{"@id":"https:\/\/luxecarexport.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/wa.me\/c\/971504542788","https:\/\/www.instagram.com\/luxecarexport\/","https:\/\/www.tiktok.com\/@luxecarexport","https:\/\/www.snapchat.com\/add\/luxecarexport23"]}]}},"_links":{"self":[{"href":"https:\/\/luxecarexport.fr\/es\/wp-json\/wp\/v2\/pages\/240450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/luxecarexport.fr\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/luxecarexport.fr\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/luxecarexport.fr\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/luxecarexport.fr\/es\/wp-json\/wp\/v2\/comments?post=240450"}],"version-history":[{"count":35,"href":"https:\/\/luxecarexport.fr\/es\/wp-json\/wp\/v2\/pages\/240450\/revisions"}],"predecessor-version":[{"id":241278,"href":"https:\/\/luxecarexport.fr\/es\/wp-json\/wp\/v2\/pages\/240450\/revisions\/241278"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/luxecarexport.fr\/es\/wp-json\/wp\/v2\/media\/241200"}],"wp:attachment":[{"href":"https:\/\/luxecarexport.fr\/es\/wp-json\/wp\/v2\/media?parent=240450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}